{"id":9552,"date":"2020-11-09T13:18:33","date_gmt":"2020-11-09T12:18:33","guid":{"rendered":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4.jpg"},"modified":"2020-11-09T13:23:48","modified_gmt":"2020-11-09T12:23:48","slug":"nickywalsh_ankerkraut_4-2","status":"inherit","type":"attachment","link":"https:\/\/agentur-rautenberg.de\/en\/nickywalsh_ankerkraut_4-2\/","title":{"rendered":"NickyWalsh_Ankerkraut_4"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-9552","attachment","type-attachment","status-inherit","hentry","media_category-anke-rabeler-en","media_category-food-photography","media_category-food-styling-en","media_category-max-faber-en","media_category-news-en","media_category-nicky-walsh-en","media_category-recipe-developement","media_category-works"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4-200x300.jpg 200w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4-400x600.jpg 400w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4.jpg 682w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Photography  Nicky Walsh<br \/>\nFood Styling Max Faber<br \/>\nRecipes: Anke Rabeler and Max Faber<br \/>\n&#8220;Ankerkraut Kids Book&#8221;<br \/>\nClient: Ankerkraut GmbH<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":682,"height":1024,"file":"2020\/11\/NickyWalsh_Ankerkraut_4.jpg","sizes":{"medium":{"file":"NickyWalsh_Ankerkraut_4-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4-200x300.jpg"},"thumbnail":{"file":"NickyWalsh_Ankerkraut_4-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4-150x150.jpg"},"ar-preview-image":{"file":"NickyWalsh_Ankerkraut_4-400x600.jpg","width":400,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4-400x600.jpg"},"post-thumbnail":{"file":"NickyWalsh_Ankerkraut_4-682x510.jpg","width":682,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4-682x510.jpg"},"sow-carousel-default":{"file":"NickyWalsh_Ankerkraut_4-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4-272x182.jpg"},"full":{"file":"NickyWalsh_Ankerkraut_4.jpg","width":682,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/11\/NickyWalsh_Ankerkraut_4.jpg","_links":{"self":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media\/9552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/users\/2"}]}}