{"id":9483,"date":"2020-10-07T10:04:54","date_gmt":"2020-10-07T08:04:54","guid":{"rendered":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13.jpg"},"modified":"2026-06-18T22:52:29","modified_gmt":"2026-06-18T20:52:29","slug":"beccacrawford_die-katze-kocht-katzenberger_13-2","status":"inherit","type":"attachment","link":"https:\/\/agentur-rautenberg.de\/en\/beccacrawford_die-katze-kocht-katzenberger_13-2\/","title":{"rendered":"BeccaCrawford_die-katze-kocht-katzenberger_13"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-9483","attachment","type-attachment","status-inherit","hentry","media_category-food-styling-en","media_category-max-faber-en","media_category-news-en","media_category-works"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"300\" src=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-272x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-272x300.jpg 272w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-768x848.jpg 768w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-543x600.jpg 543w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13.jpg 927w\" sizes=\"auto, (max-width: 272px) 100vw, 272px\" \/><\/a><\/p>\n<p>Eis-Sandwich, Daniela Katzenberger<\/p>\n"},"caption":{"rendered":"<p>Food Photography Becca Crawford<br \/>\nFood Styling Max Faber<br \/>\n&#8216;Daniela Katzenberger &#8211; Die Katze kocht&#8217;<br \/>\nClient: GU<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":927,"height":1024,"file":"2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13.jpg","sizes":{"medium":{"file":"BeccaCrawford_die-katze-kocht-katzenberger_13-272x300.jpg","width":272,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-272x300.jpg"},"thumbnail":{"file":"BeccaCrawford_die-katze-kocht-katzenberger_13-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-150x150.jpg"},"medium_large":{"file":"BeccaCrawford_die-katze-kocht-katzenberger_13-768x848.jpg","width":768,"height":848,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-768x848.jpg"},"ar-preview-image":{"file":"BeccaCrawford_die-katze-kocht-katzenberger_13-543x600.jpg","width":543,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-543x600.jpg"},"post-thumbnail":{"file":"BeccaCrawford_die-katze-kocht-katzenberger_13-825x510.jpg","width":825,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-825x510.jpg"},"sow-carousel-default":{"file":"BeccaCrawford_die-katze-kocht-katzenberger_13-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13-272x182.jpg"},"full":{"file":"BeccaCrawford_die-katze-kocht-katzenberger_13.jpg","width":927,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2020\/10\/BeccaCrawford_die-katze-kocht-katzenberger_13.jpg","filename":"BeccaCrawford_die-katze-kocht-katzenberger_13.jpg","filesize":157101,"_links":{"self":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media\/9483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/users\/2"}]}}