{"id":2726,"date":"2017-02-02T10:31:59","date_gmt":"2017-02-02T09:31:59","guid":{"rendered":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd.jpg"},"modified":"2017-02-10T13:31:06","modified_gmt":"2017-02-10T12:31:06","slug":"job_7623577774fed5eea977cd-2","status":"inherit","type":"attachment","link":"https:\/\/agentur-rautenberg.de\/en\/job_7623577774fed5eea977cd-2\/","title":{"rendered":"job_7623577774fed5eea977cd"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2726","attachment","type-attachment","status-inherit","hentry","media_category-antje-plewinski-en","media_category-works"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"212\" src=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd-300x212.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd-300x212.jpg 300w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd-768x542.jpg 768w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd.jpg 776w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Food Photography Antje Plewinski<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":776,"height":548,"file":"2017\/02\/job_7623577774fed5eea977cd.jpg","sizes":{"thumbnail":{"file":"job_7623577774fed5eea977cd-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd-150x150.jpg"},"medium":{"file":"job_7623577774fed5eea977cd-300x212.jpg","width":300,"height":212,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd-300x212.jpg"},"medium_large":{"file":"job_7623577774fed5eea977cd-768x542.jpg","width":768,"height":542,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd-768x542.jpg"},"post-thumbnail":{"file":"job_7623577774fed5eea977cd-776x510.jpg","width":776,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd-776x510.jpg"},"sow-carousel-default":{"file":"job_7623577774fed5eea977cd-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd-272x182.jpg"},"full":{"file":"job_7623577774fed5eea977cd.jpg","width":776,"height":548,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/job_7623577774fed5eea977cd.jpg","_links":{"self":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media\/2726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/users\/2"}]}}