{"id":2330,"date":"2017-02-01T09:49:54","date_gmt":"2017-02-01T08:49:54","guid":{"rendered":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402.jpg"},"modified":"2017-02-01T09:56:36","modified_gmt":"2017-02-01T08:56:36","slug":"nickywalsh_150706_schneckenburger_0402-2","status":"inherit","type":"attachment","link":"https:\/\/agentur-rautenberg.de\/en\/nickywalsh_150706_schneckenburger_0402-2\/","title":{"rendered":"NickyWalsh_150706_Schneckenburger_0402"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2330","attachment","type-attachment","status-inherit","hentry","media_category-food-photography","media_category-nicky-walsh-en","media_category-reportage-en"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\u00a9 Nicky Walsh\" srcset=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-300x200.jpg 300w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-768x512.jpg 768w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402.jpg 1024w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-900x600.jpg 900w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-272x182.jpg 272w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Food Photography Nicky Walsh<br \/>\nfor Meisterb\u00e4ckerei Schneckenburger<\/p>\n"},"alt_text":"\u00a9 Nicky Walsh","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":683,"file":"2017\/02\/NickyWalsh_150706_Schneckenburger_0402.jpg","sizes":{"thumbnail":{"file":"NickyWalsh_150706_Schneckenburger_0402-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-150x150.jpg"},"medium":{"file":"NickyWalsh_150706_Schneckenburger_0402-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-300x200.jpg"},"medium_large":{"file":"NickyWalsh_150706_Schneckenburger_0402-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-768x512.jpg"},"large":{"file":"NickyWalsh_150706_Schneckenburger_0402-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-1024x683.jpg"},"ar-preview-image":{"file":"NickyWalsh_150706_Schneckenburger_0402-900x600.jpg","width":900,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-900x600.jpg"},"post-thumbnail":{"file":"NickyWalsh_150706_Schneckenburger_0402-825x510.jpg","width":825,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-825x510.jpg"},"sow-carousel-default":{"file":"NickyWalsh_150706_Schneckenburger_0402-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402-272x182.jpg"},"full":{"file":"NickyWalsh_150706_Schneckenburger_0402.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402.jpg"}},"image_meta":{"aperture":"2.8","credit":"Nicky Walsh","camera":"Canon EOS 5D Mark III","caption":"","created_timestamp":"1436269406","copyright":"Nicky Walsh","focal_length":"70","iso":"400","shutter_speed":"0.01","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2017\/02\/NickyWalsh_150706_Schneckenburger_0402.jpg","_links":{"self":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media\/2330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/users\/2"}]}}