{"id":13529,"date":"2023-05-16T18:13:13","date_gmt":"2023-05-16T16:13:13","guid":{"rendered":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear.jpg"},"modified":"2023-05-16T18:15:13","modified_gmt":"2023-05-16T16:15:13","slug":"marinajerkovic_das-magazin_bohnensuppe_tear-2","status":"inherit","type":"attachment","link":"https:\/\/agentur-rautenberg.de\/en\/marinajerkovic_das-magazin_bohnensuppe_tear-2\/","title":{"rendered":"MarinaJerkovic_das-magazin_bohnensuppe_tear"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-13529","attachment","type-attachment","status-inherit","hentry","media_category-anke-rabeler","media_category-marina-jerkovic"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"300\" src=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear-213x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear-213x300.jpg 213w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear-426x600.jpg 426w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear.jpg 727w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Food Photography Marina Jerkovic<br \/>\nFood Styling Anke Rabeler<\/p>\n<p>Das Magazin N\u00b0 27<br \/>\nClient: Tamedia AG<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":727,"height":1024,"file":"2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear.jpg","filesize":326375,"sizes":{"medium":{"file":"MarinaJerkovic_das-magazin_bohnensuppe_tear-213x300.jpg","width":213,"height":300,"filesize":24394,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear-213x300.jpg"},"thumbnail":{"file":"MarinaJerkovic_das-magazin_bohnensuppe_tear-150x150.jpg","width":150,"height":150,"filesize":10173,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear-150x150.jpg"},"ar-preview-image":{"file":"MarinaJerkovic_das-magazin_bohnensuppe_tear-426x600.jpg","width":426,"height":600,"filesize":99895,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear-426x600.jpg"},"post-thumbnail":{"file":"MarinaJerkovic_das-magazin_bohnensuppe_tear-727x510.jpg","width":727,"height":510,"filesize":170554,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear-727x510.jpg"},"sow-carousel-default":{"file":"MarinaJerkovic_das-magazin_bohnensuppe_tear-272x182.jpg","width":272,"height":182,"filesize":20919,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear-272x182.jpg"},"full":{"file":"MarinaJerkovic_das-magazin_bohnensuppe_tear.jpg","width":727,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/05\/MarinaJerkovic_das-magazin_bohnensuppe_tear.jpg","_links":{"self":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media\/13529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/users\/2"}]}}