{"id":13250,"date":"2023-03-31T13:38:37","date_gmt":"2023-03-31T11:38:37","guid":{"rendered":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger.jpg"},"modified":"2026-06-18T17:27:31","modified_gmt":"2026-06-18T15:27:31","slug":"marinajerkovic_storl_cheese-oder-hamburger-2","status":"inherit","type":"attachment","link":"https:\/\/agentur-rautenberg.de\/en\/marinajerkovic_storl_cheese-oder-hamburger-2\/","title":{"rendered":"MarinaJerkovic_Storl_Cheese-oder-Hamburger"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-13250","attachment","type-attachment","status-inherit","hentry","media_category-foodfotografie","media_category-marina-jerkovic","media_category-max-faber"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-240x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-240x300.jpg 240w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-768x960.jpg 768w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-480x600.jpg 480w, https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger.jpg 819w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Photography Marina Jerkovic<br \/>\nFood Styling Max Faber<br \/>\nfor GU<br \/>\n&#8216;Die Rezepte unseres Lebens&#8217; Christine und Ingo Storl<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":819,"height":1024,"file":"2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger.jpg","filesize":267022,"sizes":{"medium":{"file":"MarinaJerkovic_Storl_Cheese-oder-Hamburger-240x300.jpg","width":240,"height":300,"filesize":25661,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-240x300.jpg"},"thumbnail":{"file":"MarinaJerkovic_Storl_Cheese-oder-Hamburger-150x150.jpg","width":150,"height":150,"filesize":10529,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-150x150.jpg"},"medium_large":{"file":"MarinaJerkovic_Storl_Cheese-oder-Hamburger-768x960.jpg","width":768,"height":960,"filesize":207577,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-768x960.jpg"},"ar-preview-image":{"file":"MarinaJerkovic_Storl_Cheese-oder-Hamburger-480x600.jpg","width":480,"height":600,"filesize":88213,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-480x600.jpg"},"post-thumbnail":{"file":"MarinaJerkovic_Storl_Cheese-oder-Hamburger-819x510.jpg","width":819,"height":510,"filesize":148163,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-819x510.jpg"},"sow-carousel-default":{"file":"MarinaJerkovic_Storl_Cheese-oder-Hamburger-272x182.jpg","width":272,"height":182,"filesize":20926,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger-272x182.jpg"},"full":{"file":"MarinaJerkovic_Storl_Cheese-oder-Hamburger.jpg","width":819,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agentur-rautenberg.de\/wp-content\/uploads\/2023\/03\/MarinaJerkovic_Storl_Cheese-oder-Hamburger.jpg","_links":{"self":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media\/13250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agentur-rautenberg.de\/en\/wp-json\/wp\/v2\/users\/2"}]}}